{"id":6254,"date":"2026-07-15T12:29:30","date_gmt":"2026-07-15T10:29:30","guid":{"rendered":"https:\/\/www.ventanasverdun.com\/trabajos-pvc\/cerramiento-abatible\/"},"modified":"2026-07-15T12:32:52","modified_gmt":"2026-07-15T10:32:52","slug":"hinged-enclosure","status":"publish","type":"astra-portfolio","link":"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/hinged-enclosure\/","title":{"rendered":"Hinged enclosure"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6254\" class=\"elementor elementor-6254 elementor-6244\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57948b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57948b5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2201a4f\" data-id=\"2201a4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d196294 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d196294\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-04dc11e\" data-id=\"04dc11e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc7c91 elementor-widget elementor-widget-heading\" data-id=\"5fc7c91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Hinged enclosure<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-155f6a9\" data-id=\"155f6a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e6881f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6881f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-ee478c3\" data-id=\"ee478c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-651c30d\" data-id=\"651c30d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fea4d8 elementor-widget elementor-widget-heading\" data-id=\"4fea4d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Contact<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32e1fc3 elementor-widget elementor-widget-heading\" data-id=\"32e1fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:965676070\">965 676 070<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5681f0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5681f0c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27b0fab\" data-id=\"27b0fab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5871f91 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"5871f91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-6254 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5871f91\" data-elementor-lightbox-title=\"Cerramiento abatible (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjI0OCwidXJsIjoiaHR0cHM6XC9cL3d3dy52ZW50YW5hc3ZlcmR1bi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA3XC9DZXJyYW1pZW50by1hYmF0aWJsZS0zLmpwZWciLCJzbGlkZXNob3ciOiI1ODcxZjkxIn0%3D\" href='https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-3.jpeg'><img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-3.jpeg\" class=\"attachment-full size-full\" alt=\"Cerramiento abatible\" srcset=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-3.jpeg 2048w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-3-300x225.jpeg 300w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-3-1024x768.jpeg 1024w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-3-768x576.jpeg 768w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-3-1536x1152.jpeg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5871f91\" data-elementor-lightbox-title=\"Cerramiento abatible (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NjI0NiwidXJsIjoiaHR0cHM6XC9cL3d3dy52ZW50YW5hc3ZlcmR1bi5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA3XC9DZXJyYW1pZW50by1hYmF0aWJsZS0yLmpwZWciLCJzbGlkZXNob3ciOiI1ODcxZjkxIn0%3D\" href='https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-2.jpeg'><img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-2.jpeg\" class=\"attachment-full size-full\" alt=\"Cerramiento abatible\" srcset=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-2.jpeg 2048w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-2-300x225.jpeg 300w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-2-1024x768.jpeg 1024w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-2-768x576.jpeg 768w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Cerramiento-abatible-2-1536x1152.jpeg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f264c1 elementor-widget elementor-widget-heading\" data-id=\"5f264c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Other Works<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c059b3 uael-post__link-complete-yes uael-equal__height-yes uael-posts-thumbnail-ratio elementor-widget elementor-widget-uael-posts\" data-id=\"4c059b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_slides_to_show&quot;:3,&quot;classic_slides_to_show_tablet&quot;:2,&quot;classic_slides_to_show_mobile&quot;:1}\" data-widget_type=\"uael-posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-post__header\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__body\">\n\t\t\t\n\t\t\n\t\t<div class=\"uael-blog-terms-position-above_content uael-post-image-top uael-post-grid uael-posts\" data-query-type=\"custom\" data-structure=\"normal\" data-layout=\"\" data-page=\"6254\" data-skin=\"classic\" data-filter-default=\"\" data-offset-top=\"30\" >\n\n\t\t\t\t\t\t\t<div class=\"uael-post-grid__inner uael-post__columns-3 uael-post__columns-tablet-2 uael-post__columns-mobile-1\">\n\t\t\t\n<div class=\"uael-post-wrapper   \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/silver-lacquered-pvc-carpentry\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/silver-lacquered-pvc-carpentry\/\" target=\"_self\" title=\"Silver lacquered PVC carpentry\"><img decoding=\"async\" width=\"1537\" height=\"2048\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2024\/10\/Esta-semana-nos-hemos-desplazado-a-Benidorm-trabajo-realizado-en-carpinteria-de-PVC-lacado-en-plata-por-el-exterior-en-Vicarlac-lacados-del-PVC-6.jpg\" class=\"attachment-full size-full wp-image-4750\" alt=\"Ventanas de PVC lacado en plata instaladas en vivienda de Benidorm, carpinter\u00eda exterior moderna con acabado met\u00e1lico\" srcset=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2024\/10\/Esta-semana-nos-hemos-desplazado-a-Benidorm-trabajo-realizado-en-carpinteria-de-PVC-lacado-en-plata-por-el-exterior-en-Vicarlac-lacados-del-PVC-6.jpg 1537w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2024\/10\/Esta-semana-nos-hemos-desplazado-a-Benidorm-trabajo-realizado-en-carpinteria-de-PVC-lacado-en-plata-por-el-exterior-en-Vicarlac-lacados-del-PVC-6-225x300.jpg 225w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2024\/10\/Esta-semana-nos-hemos-desplazado-a-Benidorm-trabajo-realizado-en-carpinteria-de-PVC-lacado-en-plata-por-el-exterior-en-Vicarlac-lacados-del-PVC-6-769x1024.jpg 769w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2024\/10\/Esta-semana-nos-hemos-desplazado-a-Benidorm-trabajo-realizado-en-carpinteria-de-PVC-lacado-en-plata-por-el-exterior-en-Vicarlac-lacados-del-PVC-6-768x1023.jpg 768w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2024\/10\/Esta-semana-nos-hemos-desplazado-a-Benidorm-trabajo-realizado-en-carpinteria-de-PVC-lacado-en-plata-por-el-exterior-en-Vicarlac-lacados-del-PVC-6-1153x1536.jpg 1153w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Doors<\/span><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/silver-lacquered-pvc-carpentry\/\" target=\"_self\">\n\t\t\t\tSilver lacquered PVC carpentry\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-renovation-with-pvc-windows-and-doors\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-renovation-with-pvc-windows-and-doors\/\" target=\"_self\" title=\"Complete renovation with PVC windows and doors\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/05\/Reforma-completa-con-carpinteria-de-PVC-14.jpeg\" class=\"attachment-full size-full wp-image-6077\" alt=\"Reforma completa con carpinter\u00eda de PVC\" srcset=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/05\/Reforma-completa-con-carpinteria-de-PVC-14.jpeg 1600w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/05\/Reforma-completa-con-carpinteria-de-PVC-14-300x225.jpeg 300w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/05\/Reforma-completa-con-carpinteria-de-PVC-14-1024x768.jpeg 1024w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/05\/Reforma-completa-con-carpinteria-de-PVC-14-768x576.jpeg 768w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/05\/Reforma-completa-con-carpinteria-de-PVC-14-1536x1152.jpeg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Enclosures<\/span><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-renovation-with-pvc-windows-and-doors\/\" target=\"_self\">\n\t\t\t\tComplete renovation with PVC windows and doors\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-house-in-albufera-alicante\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-house-in-albufera-alicante\/\" target=\"_self\" title=\"Complete house in Albufera Alicante\"><img loading=\"lazy\" decoding=\"async\" width=\"923\" height=\"2048\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2023\/09\/Vivienda-completa-en-albufera-alicante-1-e1695203127567.jpg\" class=\"attachment-full size-full wp-image-3788\" alt=\"\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Doors<\/span><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-house-in-albufera-alicante\/\" target=\"_self\">\n\t\t\t\tComplete house in Albufera Alicante\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/casement-sliding-and-3-leaf-sliding-balcony-windows\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/casement-sliding-and-3-leaf-sliding-balcony-windows\/\" target=\"_self\" title=\"Casement, sliding and 3-leaf sliding balcony windows\"><img loading=\"lazy\" decoding=\"async\" width=\"1537\" height=\"2048\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2025\/09\/ventanas-abatibles-4.jpg\" class=\"attachment-full size-full wp-image-5314\" alt=\"Ventanas abatibles, correderas y balconeras correderas de 3 hojas\" srcset=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2025\/09\/ventanas-abatibles-4.jpg 1537w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2025\/09\/ventanas-abatibles-4-225x300.jpg 225w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2025\/09\/ventanas-abatibles-4-769x1024.jpg 769w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2025\/09\/ventanas-abatibles-4-768x1023.jpg 768w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2025\/09\/ventanas-abatibles-4-1153x1536.jpg 1153w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Doors<\/span><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/casement-sliding-and-3-leaf-sliding-balcony-windows\/\" target=\"_self\">\n\t\t\t\tCasement, sliding and 3-leaf sliding balcony windows\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-apartment-all-exterior-pvc-lacquered-in-ral-5014-color\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-apartment-all-exterior-pvc-lacquered-in-ral-5014-color\/\" target=\"_self\" title=\"Complete apartment. All exterior Pvc lacquered in RAL-5014 color\"><img loading=\"lazy\" decoding=\"async\" width=\"1537\" height=\"2048\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2023\/02\/Apartamento-completo-en-Campello-playa.-Todo-PVC-lacado-exterior-RAL-50147.jpeg\" class=\"attachment-full size-full wp-image-1281\" alt=\"\" srcset=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2023\/02\/Apartamento-completo-en-Campello-playa.-Todo-PVC-lacado-exterior-RAL-50147.jpeg 1537w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2023\/02\/Apartamento-completo-en-Campello-playa.-Todo-PVC-lacado-exterior-RAL-50147-225x300.jpeg 225w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2023\/02\/Apartamento-completo-en-Campello-playa.-Todo-PVC-lacado-exterior-RAL-50147-769x1024.jpeg 769w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2023\/02\/Apartamento-completo-en-Campello-playa.-Todo-PVC-lacado-exterior-RAL-50147-768x1023.jpeg 768w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2023\/02\/Apartamento-completo-en-Campello-playa.-Todo-PVC-lacado-exterior-RAL-50147-1153x1536.jpeg 1153w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Doors<\/span><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-apartment-all-exterior-pvc-lacquered-in-ral-5014-color\/\" target=\"_self\">\n\t\t\t\tComplete apartment. All exterior Pvc lacquered in RAL-5014 color\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-renovation-of-pvc-carpentry-in-a-chalet\/\" target=\"_self\" class=\"uael-post__complete-box-overlay\" aria-label=\"Link Complete Box\"><\/a>\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-renovation-of-pvc-carpentry-in-a-chalet\/\" target=\"_self\" title=\"Complete renovation of PVC carpentry in a chalet\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1537\" src=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Renovacion-completa-de-carpinteria-en-este-chalet-espectacular-6.jpeg\" class=\"attachment-full size-full wp-image-6185\" alt=\"\" srcset=\"https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Renovacion-completa-de-carpinteria-en-este-chalet-espectacular-6.jpeg 2048w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Renovacion-completa-de-carpinteria-en-este-chalet-espectacular-6-300x225.jpeg 300w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Renovacion-completa-de-carpinteria-en-este-chalet-espectacular-6-1024x769.jpeg 1024w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Renovacion-completa-de-carpinteria-en-este-chalet-espectacular-6-768x576.jpeg 768w, https:\/\/www.ventanasverdun.com\/wp-content\/uploads\/2026\/07\/Renovacion-completa-de-carpinteria-en-este-chalet-espectacular-6-1536x1153.jpeg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Windows<\/span><\/span><\/div>\n\t\t\t\t\t\t<h3 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/www.ventanasverdun.com\/en\/pvc-works\/complete-renovation-of-pvc-carpentry-in-a-chalet\/\" target=\"_self\">\n\t\t\t\tComplete renovation of PVC carpentry in a chalet\t\t\t<\/a>\n\n\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__footer\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":6246,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"enabled","header-above-stick-meta":"","header-main-stick-meta":"on","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[]},"astra-portfolio-categories":[23],"astra-portfolio-other-categories":[],"astra-portfolio-tags":[],"class_list":["post-6254","astra-portfolio","type-astra-portfolio","status-publish","has-post-thumbnail","hentry","astra-portfolio-categories-enclosures"],"astra-site-call-to-action":"","astra-site-open-in-new-tab":0,"astra-site-open-portfolio-in":"same-tab","astra-site-url":"","thumbnail-image-url":null,"thumbnail-image-meta":{"alt":"","title":""},"lightbox-image-url":null,"portfolio-type":"page","portfolio-video-url":"","request_time":0.4844670295715332,"_links":{"self":[{"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/astra-portfolio\/6254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/astra-portfolio"}],"about":[{"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/types\/astra-portfolio"}],"version-history":[{"count":5,"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/astra-portfolio\/6254\/revisions"}],"predecessor-version":[{"id":6259,"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/astra-portfolio\/6254\/revisions\/6259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/media\/6246"}],"wp:attachment":[{"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/media?parent=6254"}],"wp:term":[{"taxonomy":"astra-portfolio-categories","embeddable":true,"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/astra-portfolio-categories?post=6254"},{"taxonomy":"astra-portfolio-other-categories","embeddable":true,"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/astra-portfolio-other-categories?post=6254"},{"taxonomy":"astra-portfolio-tags","embeddable":true,"href":"https:\/\/www.ventanasverdun.com\/en\/wp-json\/wp\/v2\/astra-portfolio-tags?post=6254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}